{"id":1800,"date":"2013-10-04T11:11:33","date_gmt":"2013-10-04T11:11:33","guid":{"rendered":"http:\/\/www.adehon.org\/es\/?p=1800"},"modified":"2013-10-04T11:11:33","modified_gmt":"2013-10-04T11:11:33","slug":"los-mitos-sobre-la-busqueda-de-trabajo-mito-3-opta-a-tantos-puestos-de-trabajo-como-puedas","status":"publish","type":"post","link":"https:\/\/www.adehon.org\/es\/certificados_profesionalidad\/los-mitos-sobre-la-busqueda-de-trabajo-mito-3-opta-a-tantos-puestos-de-trabajo-como-puedas\/","title":{"rendered":"Los mitos sobre la b\u00fasqueda de trabajo. Mito 3: Opta a tantos puestos de trabajo como puedas"},"content":{"rendered":"<p style=\"text-align: justify;\">Algunos piensan que la mejor manera de buscar trabajo es mandar su candidatura laboral a todos los puestos de trabajo ofertados. No importan las cualificaciones exigidas por el demandante ni nuestras propias preferencias laborales.<\/p>\n<p style=\"text-align: justify;\">La argumentaci\u00f3n que presentan los seguidores de esta estrategia es que tantos mensajes tienen que dar por fin alg\u00fan resultado.<\/p>\n<p style=\"text-align: justify;\">Puede ser que esta v\u00eda sea cierta, y que de esa manera se pueda obtener finalmente un puesto de trabajo.<\/p>\n<p style=\"text-align: justify;\">Sin embargo nosotros proponemos otro camino.<\/p>\n<p style=\"text-align: justify;\">Probablemente vas a conseguir m\u00e1s r\u00e1pido un \u00e9xito si vas a determinar, antes de comenzar la b\u00fasqueda de empleo, los sitios donde est\u00e1s dispuesto a trabajar y decidir qu\u00e9 profesi\u00f3n est\u00e1s dispuesto a ejercer.<\/p>\n<p style=\"text-align: justify;\">Gracias a esto vas a poder preparar tu presentaci\u00f3n para estos sitios concretos de la mejor forma posible.<\/p>\n<p style=\"text-align: justify;\">De esta manera, <b><span style=\"text-decoration: underline;\">un curr\u00edculum adaptado al puesto que se oferte en cuesti\u00f3n tiene, con total seguridad, muchas m\u00e1s probabilidades de ser valorado por los reclutadores<\/span><\/b>.<\/p>\n<p style=\"text-align: justify;\">Por este motivo, te animamos a que adaptes tu perfil profesional al trabajo que quieres encontrar y al que ofreces tu candidatura, as\u00ed lograr\u00e1s que b\u00fasqueda de trabajo deje de parecer una pesca en agua turbia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunos piensan que la mejor manera de buscar trabajo es mandar su candidatura laboral a todos los puestos de trabajo ofertados. No importan las cualificaciones exigidas por el demandante ni nuestras propias preferencias laborales. La argumentaci\u00f3n que presentan los seguidores de esta estrategia es que tantos mensajes tienen que dar por fin alg\u00fan resultado. Puede ser que esta v\u00eda sea cierta, y que de esa manera se pueda obtener finalmente un puesto de trabajo. Sin embargo nosotros proponemos otro camino. Probablemente vas a conseguir m\u00e1s r\u00e1pido un \u00e9xito si vas a determinar, antes de comenzar la b\u00fasqueda de empleo, los sitios donde est\u00e1s dispuesto a trabajar y decidir qu\u00e9 profesi\u00f3n est\u00e1s dispuesto a ejercer. Gracias a esto vas a poder preparar tu presentaci\u00f3n para estos sitios concretos de la mejor forma posible. De esta manera, un curr\u00edculum adaptado al puesto que se oferte en cuesti\u00f3n tiene, con total seguridad, muchas m\u00e1s probabilidades de ser valorado por los reclutadores. Por este&nbsp;<a href=\"https:\/\/www.adehon.org\/es\/certificados_profesionalidad\/los-mitos-sobre-la-busqueda-de-trabajo-mito-3-opta-a-tantos-puestos-de-trabajo-como-puedas\/\" class=\"read-more\">Continuar Leyendo<\/a><\/p>\n","protected":false},"author":1,"featured_media":1801,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44,41,42,46,48,47,45,43],"tags":[],"class_list":["post-1800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-certificados_idiomas","category-certificados_profesionalidad","category-contrato_trabajo_dual","category-e-learning","category-noticias_generales_empleo","category-nuevas_tendencias_empleo","category-ofertas_empleo","category-practicas_empresa","cat-44-id","cat-41-id","cat-42-id","cat-46-id","cat-48-id","cat-47-id","cat-45-id","cat-43-id"],"_links":{"self":[{"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/posts\/1800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/comments?post=1800"}],"version-history":[{"count":1,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/posts\/1800\/revisions"}],"predecessor-version":[{"id":1802,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/posts\/1800\/revisions\/1802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/media\/1801"}],"wp:attachment":[{"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/media?parent=1800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/categories?post=1800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adehon.org\/es\/wp-json\/wp\/v2\/tags?post=1800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}